{"id":39139,"date":"2021-10-11T13:13:26","date_gmt":"2021-10-11T11:13:26","guid":{"rendered":"https:\/\/dev.lanificiodellolivo.com\/product\/senza-categoria\/oscar-ai20\/"},"modified":"2021-10-11T13:13:26","modified_gmt":"2021-10-11T11:13:26","slug":"oscar-ai20","status":"publish","type":"product","link":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/","title":{"rendered":"Oscar AI20"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":36260,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[6219,337],"product_tag":[],"class_list":["post-39139","product","type-product","status-publish","has-post-thumbnail","product_cat-autunno-inverno-19-20","product_cat-collezioni-precedenti","first","instock","sold-individually","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oscar AI20 | Lanificio dell&#039;Olivo<\/title>\n<meta name=\"description\" content=\"Oscar AI20 | Lanificio dell&#039;Olivo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oscar AI20 | Lanificio dell&#039;Olivo\" \/>\n<meta property=\"og:description\" content=\"Oscar AI20 | Lanificio dell&#039;Olivo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/\" \/>\n<meta property=\"og:site_name\" content=\"Lanificio dell&#039;Olivo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2021\/10\/08095558\/T_LesOxides_Oscar_03_AW20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"1410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/\",\"url\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/\",\"name\":\"Oscar AI20 | Lanificio dell&#039;Olivo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/08095558\\\/T_LesOxides_Oscar_03_AW20.jpg\",\"datePublished\":\"2021-10-11T11:13:26+00:00\",\"description\":\"Oscar AI20 | Lanificio dell&#039;Olivo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/08095558\\\/T_LesOxides_Oscar_03_AW20.jpg\",\"contentUrl\":\"https:\\\/\\\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/08095558\\\/T_LesOxides_Oscar_03_AW20.jpg\",\"width\":1050,\"height\":1410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/prodotti\\\/collezioni-precedenti\\\/autunno-inverno-19-20\\\/oscar-ai20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/lanificiodellolivo.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oscar AI20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/\",\"name\":\"Lanificio dell&#039;Olivo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#organization\",\"name\":\"Lanificio dell'Olivo S.p.a.\",\"url\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/19174311\\\/Lanificio-dellOlivo_logo_verde.svg\",\"contentUrl\":\"https:\\\/\\\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/19174311\\\/Lanificio-dellOlivo_logo_verde.svg\",\"width\":323,\"height\":104,\"caption\":\"Lanificio dell'Olivo S.p.a.\"},\"image\":{\"@id\":\"https:\\\/\\\/lanificiodellolivo.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oscar AI20 | Lanificio dell&#039;Olivo","description":"Oscar AI20 | Lanificio dell&#039;Olivo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/","og_locale":"it_IT","og_type":"article","og_title":"Oscar AI20 | Lanificio dell&#039;Olivo","og_description":"Oscar AI20 | Lanificio dell&#039;Olivo","og_url":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/","og_site_name":"Lanificio dell&#039;Olivo","og_image":[{"width":1050,"height":1410,"url":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2021\/10\/08095558\/T_LesOxides_Oscar_03_AW20.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/","url":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/","name":"Oscar AI20 | Lanificio dell&#039;Olivo","isPartOf":{"@id":"https:\/\/lanificiodellolivo.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/#primaryimage"},"image":{"@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/#primaryimage"},"thumbnailUrl":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2021\/10\/08095558\/T_LesOxides_Oscar_03_AW20.jpg","datePublished":"2021-10-11T11:13:26+00:00","description":"Oscar AI20 | Lanificio dell&#039;Olivo","breadcrumb":{"@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/#primaryimage","url":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2021\/10\/08095558\/T_LesOxides_Oscar_03_AW20.jpg","contentUrl":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2021\/10\/08095558\/T_LesOxides_Oscar_03_AW20.jpg","width":1050,"height":1410},{"@type":"BreadcrumbList","@id":"https:\/\/lanificiodellolivo.com\/it\/prodotti\/collezioni-precedenti\/autunno-inverno-19-20\/oscar-ai20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lanificiodellolivo.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lanificiodellolivo.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Oscar AI20"}]},{"@type":"WebSite","@id":"https:\/\/lanificiodellolivo.com\/it\/#website","url":"https:\/\/lanificiodellolivo.com\/it\/","name":"Lanificio dell&#039;Olivo","description":"","publisher":{"@id":"https:\/\/lanificiodellolivo.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lanificiodellolivo.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lanificiodellolivo.com\/it\/#organization","name":"Lanificio dell'Olivo S.p.a.","url":"https:\/\/lanificiodellolivo.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lanificiodellolivo.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2020\/06\/19174311\/Lanificio-dellOlivo_logo_verde.svg","contentUrl":"https:\/\/wpmedia-lanificiodellolivocom.s3.eu-central-1.amazonaws.com\/wp-content\/uploads\/2020\/06\/19174311\/Lanificio-dellOlivo_logo_verde.svg","width":323,"height":104,"caption":"Lanificio dell'Olivo S.p.a."},"image":{"@id":"https:\/\/lanificiodellolivo.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/product\/39139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/comments?post=39139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/media\/36260"}],"wp:attachment":[{"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/media?parent=39139"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/product_brand?post=39139"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/product_cat?post=39139"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lanificiodellolivo.com\/it\/wp-json\/wp\/v2\/product_tag?post=39139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}